{"id":86786,"date":"2026-05-03T14:25:46","date_gmt":"2026-05-03T14:25:46","guid":{"rendered":"https:\/\/neu.aponi.es\/?page_id=86786"},"modified":"2026-07-25T17:17:38","modified_gmt":"2026-07-25T17:17:38","slug":"both-ends-of-the-leash","status":"publish","type":"page","link":"https:\/\/aponi.es\/en\/beide-enden-der-leine\/","title":{"rendered":"\u201eBoth ends of the leash\u201c\u00a0"},"content":{"rendered":"\n[et_pb_section fb_built=&#8220;1&#8243; custom_padding_last_edited=&#8220;on|phone&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;rgba(165,226,217,0.31)&#8220; custom_margin_tablet=&#8220;&#8220; custom_margin_phone=&#8220;||0px||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; custom_padding_tablet=&#8220;70px||||false|false&#8220; custom_padding_phone=&#8220;||0px||false|false&#8220; animation_style=&#8220;fade&#8220; da_disable_devices=&#8220;off|off|off&#8220; global_colors_info=&#8220;{}&#8220; da_is_popup=&#8220;off&#8220; da_exit_intent=&#8220;off&#8220; da_has_close=&#8220;on&#8220; da_alt_close=&#8220;off&#8220; da_dark_close=&#8220;off&#8220; da_not_modal=&#8220;on&#8220; da_is_singular=&#8220;off&#8220; da_with_loader=&#8220;off&#8220; da_has_shadow=&#8220;on&#8220;][et_pb_row make_equal=&#8220;on&#8220; custom_padding_last_edited=&#8220;on|phone&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;12px|||||&#8220; custom_padding_tablet=&#8220;12px|||||&#8220; custom_padding_phone=&#8220;0px||||false|false&#8220; animation_style=&#8220;fade&#8220; custom_css_main_element=&#8220;align-items:center;&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;Poppins|300|||||||&#8220; text_text_color=&#8220;#333333&#8243; text_font_size=&#8220;20px&#8220; text_line_height=&#8220;1.8em&#8220; header_3_font=&#8220;Libre Caslon Text||||||||&#8220; header_3_text_align=&#8220;left&#8220; header_3_text_color=&#8220;#056F70&#8243; header_3_font_size=&#8220;30px&#8220; header_3_line_height=&#8220;1.4em&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;30px||||false|false&#8220; custom_margin_tablet=&#8220;-10px||||false|false&#8220; custom_margin_phone=&#8220;-10px||||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; header_3_text_align_tablet=&#8220;left&#8220; header_3_text_align_phone=&#8220;left&#8220; header_3_text_align_last_edited=&#8220;on|tablet&#8220; header_3_font_size_tablet=&#8220;28px&#8220; header_3_font_size_phone=&#8220;28px&#8220; header_3_font_size_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<h3>\u201eBeide Enden der Leine\u201c<br \/>Wenn Symptome mehr sind als nur Symptome<\/h3>\n<p><strong>8 Wochen systemische Ursachenarbeit f\u00fcr dich und deinen Hund<\/strong><\/p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;Poppins|300|||||||&#8220; text_text_color=&#8220;#333333&#8243; text_font_size=&#8220;18px&#8220; text_line_height=&#8220;1.8em&#8220; custom_margin=&#8220;-5px||||false|false&#8220; custom_margin_tablet=&#8220;-15px||||false|false&#8220; custom_margin_phone=&#8220;-15px||||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<p>Du warst bei den verschiedenen Tier\u00e4rzten, hast Futter umgestellt und unterschiedliche Ans\u00e4tze probiert. Du hast alles versucht. Und trotzdem kommt es immer wieder zur\u00fcck.<\/p>\n<p>Und ganz ehrlich? Es macht dich langsam verr\u00fcckt.<\/p>\n<p>Du beobachtest st\u00e4ndig, analysierst jede Kleinigkeit, dein Kopf l\u00e4uft dauerhaft und dein K\u00f6rper ist im Dauerstress.\u201c<\/p>\n<p>Die meisten schauen nur auf deinen Hund, doch genau da liegt das Problem. <strong>Denn Symptome entstehen nicht isoliert. Sie entstehen in einem System.<\/strong> Dein Hund bringt seine Themen mit. Du bringst deine mit. Und beides beeinflusst sich, jeden Tag. Was sich bei deinem Hund zeigt, ist oft nur ein Teil des Ganzen.<\/p>\n<p>Die meisten sehen nur das Offensichtliche, die Symptome, die Reaktionen. Und genau deshalb dreht ihr euch im Kreis.<\/p>\n<p>In meiner <strong>26-j\u00e4hrigen therapeutischen Erfahrung, davon \u00fcber 11 Jahre in der Naturheilkunde<\/strong>, zeigt sich immer wieder: <strong>Tiefgreifende Ver\u00e4nderung<\/strong> entsteht<b>\u00a0<\/b>erst, wenn wir <strong>beide Systeme<\/strong> gemeinsam betrachten, <strong>Mensch und Tier.<\/strong><b><br \/><\/b><b><\/b><\/p>\n<p><strong>Ich arbeite nicht symptomorientiert. Ich arbeite mit euch als System.<\/strong> Das bedeutet: Ich schaue euch beide an, k\u00f6rperlich, emotional und im Alltag.<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_2,1_2&#8243; use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;2&#8243; make_equal=&#8220;on&#8220; custom_padding_last_edited=&#8220;on|phone&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; width=&#8220;90%&#8220; width_tablet=&#8220;90%&#8220; width_phone=&#8220;80%&#8220; width_last_edited=&#8220;on|desktop&#8220; max_width=&#8220;1270px&#8220; max_width_tablet=&#8220;90%&#8220; max_width_phone=&#8220;90%&#8220; max_width_last_edited=&#8220;on|tablet&#8220; custom_margin=&#8220;32px|auto|60px|auto|false|false&#8220; custom_margin_tablet=&#8220;0px||||false|false&#8220; custom_margin_phone=&#8220;0px||||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; custom_padding_tablet=&#8220;20px||0px|||&#8220; custom_padding_phone=&#8220;20px||0px||false|false&#8220; animation_style=&#8220;fade&#8220; border_color_top=&#8220;#056F70&#8243; border_width_top_tablet=&#8220;0px&#8220; border_width_top_phone=&#8220;0px&#8220; border_width_top_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;160px|||58px|false|false&#8220; custom_padding_tablet=&#8220;40px||80px|0px|false|false&#8220; custom_padding_phone=&#8220;60px||40px|0px|false|false&#8220; custom_padding_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; header_3_font=&#8220;Libre Caslon Text||||||||&#8220; header_3_text_align=&#8220;left&#8220; header_3_text_color=&#8220;#056F70&#8243; header_3_font_size=&#8220;30px&#8220; header_3_line_height=&#8220;1.4em&#8220; max_width=&#8220;700px&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;30px||||false|false&#8220; custom_margin_tablet=&#8220;-10px||||false|false&#8220; custom_margin_phone=&#8220;-45px||||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; header_3_font_size_tablet=&#8220;28px&#8220; header_3_font_size_phone=&#8220;28px&#8220; header_3_font_size_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<h3>Wir arbeiten auf 3 Ebenen:<\/h3>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;Poppins|300|||||||&#8220; text_text_color=&#8220;#333333&#8243; text_font_size=&#8220;18px&#8220; text_line_height=&#8220;1.8em&#8220; custom_margin=&#8220;-5px||||false|false&#8220; custom_margin_tablet=&#8220;-15px||||false|false&#8220; custom_margin_phone=&#8220;-15px||||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<ul>\n<li><strong> K\u00f6rper<br \/><\/strong> Belastungen, Entz\u00fcndungen, Regulation und k\u00f6rperliche Ursachen<br \/>\u3164\u3164<\/li>\n<li><strong> Nervensystem &amp; Verhalten<br \/><\/strong> Stress, Anspannung, Reaktionen<br \/>\u3164\u3164<\/li>\n<li><strong> Alltag &amp; Umfeld<br \/><\/strong> Ern\u00e4hrung, Lebensweise, \u00e4u\u00dfere Einfl\u00fcsse<\/li>\n<\/ul>\n<p>Alles h\u00e4ngt zusammen und genau dort setzen wir an.<\/p>[\/et_pb_text][et_pb_button button_url=&#8220;#footer&#8220; button_text=&#8220;begleitung anfragen&#8220; button_alignment=&#8220;left&#8220; button_alignment_tablet=&#8220;left&#8220; button_alignment_phone=&#8220;center&#8220; button_alignment_last_edited=&#8220;off|desktop&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;15px&#8220; button_text_color=&#8220;#000000&#8243; button_bg_color=&#8220;#A5E2D9&#8243; button_border_width=&#8220;0px&#8220; button_border_radius=&#8220;100px&#8220; button_letter_spacing=&#8220;1px&#8220; button_font=&#8220;Poppins|500||on|||||&#8220; button_use_icon=&#8220;off&#8220; custom_margin=&#8220;50px||||false|false&#8220; custom_padding=&#8220;23px|55px|21px|55px|false|true&#8220; custom_padding_tablet=&#8220;23px|55px|21px|55px|false|true&#8220; custom_padding_phone=&#8220;19px|25px|16px|25px|false|true&#8220; custom_padding_last_edited=&#8220;on|phone&#8220; button_text_size_tablet=&#8220;15px&#8220; button_text_size_phone=&#8220;14px&#8220; button_text_size_last_edited=&#8220;on|phone&#8220; box_shadow_style=&#8220;preset1&#8243; global_colors_info=&#8220;{}&#8220; button_text_color__hover_enabled=&#8220;off|desktop&#8220; button_text_color__hover=&#8220;#ffffff&#8220; button_bg_color__hover_enabled=&#8220;off|desktop&#8220; button_bg_color__hover=&#8220;#75a099&#8243; button_bg_enable_color__hover=&#8220;on&#8220; button_border_color__hover_enabled=&#8220;on|hover&#8220; button_border_color__hover=&#8220;#2A3F75&#8243; button_letter_spacing__hover_enabled=&#8220;on|desktop&#8220; button_letter_spacing__hover=&#8220;1px&#8220; transform_styles__hover_enabled=&#8220;on|desktop&#8220; transform_scale__hover=&#8220;105%|105%&#8220; transform_scale__hover_enabled=&#8220;on|desktop&#8220; transform_translate__hover_enabled=&#8220;on|desktop&#8220; transform_rotate__hover_enabled=&#8220;on|desktop&#8220; transform_skew__hover_enabled=&#8220;on|desktop&#8220; transform_origin__hover_enabled=&#8220;on|desktop&#8220;][\/et_pb_button][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; scroll_vertical_motion_enable=&#8220;on&#8220; scroll_vertical_motion=&#8220;0|50|50|100|0.5|0|0.5&#8243; scroll_vertical_motion_tablet=&#8220;0|50|50|100|0|0|0&#8243; scroll_vertical_motion_phone=&#8220;0|50|50|100|0|0|0&#8243; scroll_vertical_motion_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/aponi.es\/wp-content\/uploads\/2026\/01\/Aponi_22.webp&#8220; alt=&#8220;Aponi Naturopat\u00eda&#8220; title_text=&#8220;Aponi Naturopat\u00eda&#8220; align=&#8220;center&#8220; align_tablet=&#8220;right&#8220; align_phone=&#8220;right&#8220; align_last_edited=&#8220;on|phone&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; width=&#8220;450px&#8220; width_tablet=&#8220;400px&#8220; width_phone=&#8220;300px&#8220; width_last_edited=&#8220;on|phone&#8220; custom_margin_tablet=&#8220;-40px||-70px||false|false&#8220; custom_margin_phone=&#8220;0px||66px||false|false&#8220; custom_margin_last_edited=&#8220;on|tablet&#8220; global_colors_info=&#8220;{}&#8220; width__hover_enabled=&#8220;off|desktop&#8220;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; custom_padding_last_edited=&#8220;on|tablet&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;RGBA(255,255,255,0)&#8220; custom_padding=&#8220;100px||59px|||&#8220; custom_padding_tablet=&#8220;||92px||false|false&#8220; custom_padding_phone=&#8220;0px||42px||false|false&#8220; da_disable_devices=&#8220;off|off|off&#8220; global_colors_info=&#8220;{}&#8220; da_is_popup=&#8220;off&#8220; da_exit_intent=&#8220;off&#8220; da_has_close=&#8220;on&#8220; da_alt_close=&#8220;off&#8220; da_dark_close=&#8220;off&#8220; da_not_modal=&#8220;on&#8220; da_is_singular=&#8220;off&#8220; da_with_loader=&#8220;off&#8220; da_has_shadow=&#8220;on&#8220;][et_pb_row use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;2&#8243; make_equal=&#8220;on&#8220; custom_padding_last_edited=&#8220;on|phone&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#FFFFFF&#8220; width=&#8220;90%&#8220; width_tablet=&#8220;90%&#8220; width_phone=&#8220;90%&#8220; width_last_edited=&#8220;on|desktop&#8220; max_width=&#8220;1170px&#8220; max_width_tablet=&#8220;90%&#8220; max_width_phone=&#8220;90%&#8220; max_width_last_edited=&#8220;on|tablet&#8220; custom_padding=&#8220;60px|60px|60px|60px|false|true&#8220; custom_padding_tablet=&#8220;60px|30px|60px|30px|false|false&#8220; custom_padding_phone=&#8220;60px|30px|60px|30px|false|false&#8220; animation_style=&#8220;fade&#8220; border_radii=&#8220;on|20px|20px|20px|20px&#8220; border_color_right=&#8220;#056F70&#8243; border_color_bottom=&#8220;#056F70&#8243; box_shadow_style=&#8220;preset1&#8243; box_shadow_color=&#8220;#056F70&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_icon font_icon=&#8220;&#xf2f1;||fa||900&#8243; icon_color=&#8220;#056F70&#8243; icon_width=&#8220;45px&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;5px|||||&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_icon][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; header_3_font=&#8220;Libre Caslon Text||||||||&#8220; header_3_text_align=&#8220;center&#8220; header_3_text_color=&#8220;#056F70&#8243; header_3_font_size=&#8220;30px&#8220; header_3_line_height=&#8220;1.4em&#8220; max_width=&#8220;700px&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;30px||||false|false&#8220; custom_margin_tablet=&#8220;-10px||||false|false&#8220; custom_margin_phone=&#8220;-10px||||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; header_3_font_size_tablet=&#8220;28px&#8220; header_3_font_size_phone=&#8220;28px&#8220; header_3_font_size_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<h3>Was sich ver\u00e4ndern kann<\/h3>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;Poppins|300|||||||&#8220; text_text_color=&#8220;#333333&#8243; text_font_size=&#8220;18px&#8220; text_line_height=&#8220;1.8em&#8220; text_orientation=&#8220;center&#8220; custom_margin=&#8220;-5px||||false|false&#8220; custom_margin_tablet=&#8220;-15px||||false|false&#8220; custom_margin_phone=&#8220;-15px||||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<p>Nicht perfekt jedoch sp\u00fcrbar und vor allem stabil.<\/p>\n<p><strong><\/strong><\/p>\n<p><strong> f\u00fcr deinen Hund: <\/strong><\/p>\n<p>\u2022 wird ruhiger und belastbarer<\/p>\n<p>\u2022 ist wieder mehr bei sich<\/p>\n<p>\u2022 Symptome k\u00f6nnen in den Hintergrund treten oder sich aufl\u00f6sen<\/p>\n<p>\u2022 hat wieder mehr Energie &amp; Lebensfreude<\/p>\n<p><strong><\/strong><\/p>\n<p><strong> f\u00fcr dich: <\/strong><\/p>\n<p>\u2022 du steigst aus dem Dauerdenken aus<\/p>\n<p>\u2022 dein K\u00f6rper kommt endlich zur Ruhe<\/p>\n<p>\u2022 dein Kopf wird klar<\/p>\n<p>\u2022 du bekommst wieder Orientierung<\/p>\n<p>\u2022 du hast wieder mehr Energie f\u00fcr deinen Alltag<\/p>\n<p><strong>Du h\u00f6rst auf, st\u00e4ndig zu kontrollieren und beginnst wieder zu vertrauen.<\/strong><\/p>[\/et_pb_text][et_pb_button button_text=&#8220;Zwischenblick jetzt buchen&#8220; button_alignment=&#8220;center&#8220; button_alignment_tablet=&#8220;center&#8220; button_alignment_phone=&#8220;center&#8220; button_alignment_last_edited=&#8220;off|desktop&#8220; disabled_on=&#8220;on|on|on&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;15px&#8220; button_text_color=&#8220;#000000&#8243; button_bg_color=&#8220;#A5E2D9&#8243; button_border_width=&#8220;0px&#8220; button_border_radius=&#8220;100px&#8220; button_letter_spacing=&#8220;1px&#8220; button_font=&#8220;Gothic A1|600||on|||||&#8220; button_use_icon=&#8220;off&#8220; custom_margin=&#8220;50px||||false|false&#8220; custom_padding=&#8220;23px|55px|21px|55px|false|true&#8220; custom_padding_tablet=&#8220;23px|55px|21px|55px|false|true&#8220; custom_padding_phone=&#8220;19px|25px|16px|25px|false|true&#8220; custom_padding_last_edited=&#8220;on|phone&#8220; button_text_size_tablet=&#8220;15px&#8220; button_text_size_phone=&#8220;14px&#8220; button_text_size_last_edited=&#8220;on|phone&#8220; box_shadow_style=&#8220;preset1&#8243; disabled=&#8220;on&#8220; global_colors_info=&#8220;{}&#8220; button_text_color__hover_enabled=&#8220;off|desktop&#8220; button_text_color__hover=&#8220;#ffffff&#8220; button_bg_color__hover_enabled=&#8220;off|desktop&#8220; button_bg_color__hover=&#8220;#75a099&#8243; button_bg_enable_color__hover=&#8220;on&#8220; button_border_color__hover_enabled=&#8220;on|hover&#8220; button_border_color__hover=&#8220;#2A3F75&#8243; button_letter_spacing__hover_enabled=&#8220;on|desktop&#8220; button_letter_spacing__hover=&#8220;1px&#8220; transform_styles__hover_enabled=&#8220;on|desktop&#8220; transform_scale__hover=&#8220;105%|105%&#8220; transform_scale__hover_enabled=&#8220;on|desktop&#8220; transform_translate__hover_enabled=&#8220;on|desktop&#8220; transform_rotate__hover_enabled=&#8220;on|desktop&#8220; transform_skew__hover_enabled=&#8220;on|desktop&#8220; transform_origin__hover_enabled=&#8220;on|desktop&#8220;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; custom_padding_last_edited=&#8220;on|phone&#8220; module_id=&#8220;deinzwischenblick&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; use_background_color_gradient=&#8220;on&#8220; background_color_gradient_stops=&#8220;#ffffff 32%|rgba(165,226,217,0.33) 51%&#8220; background_color_gradient_start=&#8220;#ffffff&#8220; background_color_gradient_start_position=&#8220;50%&#8220; background_color_gradient_end=&#8220;#FDF5F3&#8243; background_color_gradient_end_position=&#8220;0%&#8220; custom_padding=&#8220;20px||94px||false|false&#8220; custom_padding_tablet=&#8220;20px||94px||false|false&#8220; custom_padding_phone=&#8220;0px||44px||false|false&#8220; da_disable_devices=&#8220;off|off|off&#8220; global_colors_info=&#8220;{}&#8220; da_is_popup=&#8220;off&#8220; da_exit_intent=&#8220;off&#8220; da_has_close=&#8220;on&#8220; da_alt_close=&#8220;off&#8220; da_dark_close=&#8220;off&#8220; da_not_modal=&#8220;on&#8220; da_is_singular=&#8220;off&#8220; da_with_loader=&#8220;off&#8220; da_has_shadow=&#8220;on&#8220;][et_pb_row custom_padding_last_edited=&#8220;on|phone&#8220; module_id=&#8220;begleitunganfragen&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;1px|auto|92px|auto|false|false&#8220; custom_margin_tablet=&#8220;-40px|auto||auto|false|false&#8220; custom_margin_phone=&#8220;12px||0px||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; custom_padding=&#8220;||0px|||&#8220; custom_padding_tablet=&#8220;||9px|||&#8220; custom_padding_phone=&#8220;||0px||false|false&#8220; animation_style=&#8220;fade&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_icon font_icon=&#8220;&#xf5bb;||fa||900&#8243; icon_color=&#8220;#056F70&#8243; icon_width=&#8220;45px&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;5px|||||&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_icon][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; header_3_font=&#8220;Libre Caslon Text||||||||&#8220; header_3_text_align=&#8220;center&#8220; header_3_text_color=&#8220;#056F70&#8243; header_3_font_size=&#8220;30px&#8220; header_3_line_height=&#8220;1.4em&#8220; max_width=&#8220;700px&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;30px||28px||false|false&#8220; custom_margin_tablet=&#8220;-10px||||false|false&#8220; custom_margin_phone=&#8220;-10px||||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; header_3_font_size_tablet=&#8220;28px&#8220; header_3_font_size_phone=&#8220;28px&#8220; header_3_font_size_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<h3>Stell dir vor:<\/h3>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;Poppins|300|||||||&#8220; text_text_color=&#8220;#333333&#8243; text_font_size=&#8220;18px&#8220; text_line_height=&#8220;1.8em&#8220; custom_margin=&#8220;-5px||||false|false&#8220; custom_margin_tablet=&#8220;-15px||||false|false&#8220; custom_margin_phone=&#8220;-15px||||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<p style=\"text-align: center;\">Du wachst morgens auf, dein erster Blick zu deinem Hund ist ruhig, kein innerer Alarm, kein sofortiges Analysieren. Dein K\u00f6rper ist entspannt und dein Kopf ist klar. Dein Hund ist stabil, voller Lebensfreude und vor allem wieder ganz er selbst.<span class=\"Apple-converted-space\">\u00a0 <\/span><strong>Und euer Alltag f\u00fchlt sich endlich wieder leicht und harmonisch an.<\/strong><\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row make_equal=&#8220;on&#8220; custom_padding_last_edited=&#8220;on|tablet&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; width_tablet=&#8220;&#8220; width_phone=&#8220;90%&#8220; width_last_edited=&#8220;on|phone&#8220; max_width=&#8220;800px&#8220; max_width_tablet=&#8220;600px&#8220; max_width_phone=&#8220;600px&#8220; max_width_last_edited=&#8220;on|desktop&#8220; custom_margin=&#8220;7px|auto||auto|false|false&#8220; custom_padding=&#8220;6px|||||&#8220; custom_padding_tablet=&#8220;0px||||false|false&#8220; custom_padding_phone=&#8220;60px||||false|false&#8220; animation_style=&#8220;fade&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#FFFFFF&#8220; custom_padding=&#8220;0px|20px|40px|20px|false|false&#8220; custom_css_main_element=&#8220;display:flex;||flex-direction:column;&#8220; border_radii=&#8220;on|20px|20px|20px|20px&#8220; box_shadow_style=&#8220;preset1&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;Poppins|300|||||||&#8220; text_text_color=&#8220;#333333&#8243; text_font_size=&#8220;20px&#8220; text_line_height=&#8220;1.8em&#8220; header_3_font=&#8220;Libre Caslon Text||||||||&#8220; header_3_text_align=&#8220;left&#8220; header_3_text_color=&#8220;#056F70&#8243; header_3_font_size=&#8220;30px&#8220; header_3_line_height=&#8220;1.4em&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;30px||||false|false&#8220; custom_margin_tablet=&#8220;30px||||false|false&#8220; custom_margin_phone=&#8220;30px||||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; header_3_text_align_tablet=&#8220;left&#8220; header_3_text_align_phone=&#8220;left&#8220; header_3_text_align_last_edited=&#8220;on|tablet&#8220; header_3_font_size_tablet=&#8220;28px&#8220; header_3_font_size_phone=&#8220;28px&#8220; header_3_font_size_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<h3 style=\"text-align: center;\">\u201eBeide Enden der Leine\u201c<\/h3>\n<p style=\"text-align: center;\"><strong> 8 Wochen systemische Ursachen- Begleitung f\u00fcr dich und deinen Hund<\/strong><\/p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;Poppins|300|||||||&#8220; text_text_color=&#8220;#333333&#8243; text_font_size=&#8220;18px&#8220; text_line_height=&#8220;1.8em&#8220; custom_margin=&#8220;-5px||||false|false&#8220; custom_margin_tablet=&#8220;-15px||||false|false&#8220; custom_margin_phone=&#8220;-15px||||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<p style=\"text-align: center;\">Damit euer System wieder zur Ruhe kommt und ihr endlich versteht, was wirklich dahintersteckt.<\/p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;Poppins|300|||||||&#8220; text_text_color=&#8220;#333333&#8243; text_font_size=&#8220;18px&#8220; text_line_height=&#8220;1.8em&#8220; custom_margin=&#8220;20px||||false|false&#8220; custom_margin_tablet=&#8220;-15px||||false|false&#8220; custom_margin_phone=&#8220;-15px||||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<p style=\"text-align: center;\"><strong> Was dich in den 8 Wochen erwartet:<\/strong><\/p>\n<p style=\"text-align: center;\">\u2022 Tiefe Analyse von dir, deinem Hund &amp; eurer Dynamik<\/p>\n<p style=\"text-align: center;\">\u2022 Klarheit \u00fcber die die Zusammenh\u00e4nge hinter den Symptomen<\/p>\n<p style=\"text-align: center;\">\u2022 Regulation f\u00fcr euch beide, k\u00f6rperlich &amp; emotional<\/p>\n<p style=\"text-align: center;\">\u2022 individuelle naturheilkundliche Impulse<\/p>\n<p style=\"text-align: center;\">\u2022 Pers\u00f6nliches Coaching f\u00fcr dich<\/p>\n<p style=\"text-align: center;\">\u2022 regelm\u00e4\u00dfige 1:1 Sessions (online)<\/p>\n<p style=\"text-align: center;\">\u2022 kontinuierliche Begleitung &amp; Anpassung<\/p>\n<p style=\"text-align: center;\"><strong>Keine Standardl\u00f6sung, sondern individuell auf euch abgestimmt.<\/strong><strong><\/strong><\/p>\n<p style=\"text-align: center;\"><em><strong>Deine Investition:<\/strong><\/em><\/p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;Poppins|300|||||||&#8220; text_text_color=&#8220;#056F70&#8243; text_font_size=&#8220;25px&#8220; text_line_height=&#8220;1.8em&#8220; custom_margin=&#8220;-5px||||false|false&#8220; custom_margin_tablet=&#8220;-15px||||false|false&#8220; custom_margin_phone=&#8220;-15px||||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<p style=\"text-align: center;\"><strong>2.400 \u20ac <\/strong><\/p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;Poppins|300|||||||&#8220; text_text_color=&#8220;#333333&#8243; text_font_size=&#8220;18px&#8220; text_line_height=&#8220;1.8em&#8220; custom_margin=&#8220;20px||||false|false&#8220; custom_margin_tablet=&#8220;-15px||||false|false&#8220; custom_margin_phone=&#8220;-15px||||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<p style=\"text-align: center;\">Du investierst nicht in ein Programm, sondern in:<\/p>\n<p style=\"text-align: center;\"><span>\u2714<\/span> Ruhe in deinem Kopf<br \/><span>\u2714<\/span> Stabilit\u00e4t bei deinem Hund<br \/><span>\u2714<\/span> Einen Alltag ohne st\u00e4ndige Anspannung und Angst<\/p>\n<p style=\"text-align: center;\"><em>Du buchst keine Methode. Du buchst Klarheit, Orientierung und echte Ver\u00e4nderung.<\/em><\/p>[\/et_pb_text][et_pb_button button_url=&#8220;#footer&#8220; url_new_window=&#8220;on&#8220; button_text=&#8220;jetzt anfragen&#8220; button_alignment=&#8220;center&#8220; disabled_on=&#8220;off|off|off&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;15px&#8220; button_text_color=&#8220;#000000&#8243; button_bg_color=&#8220;#A5E2D9&#8243; button_border_width=&#8220;0px&#8220; button_border_radius=&#8220;100px&#8220; button_letter_spacing=&#8220;1px&#8220; button_font=&#8220;Poppins|||on|||||&#8220; button_use_icon=&#8220;off&#8220; custom_margin=&#8220;50px||||false|false&#8220; custom_margin_tablet=&#8220;50px||||false|false&#8220; custom_margin_phone=&#8220;25px||||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; custom_padding=&#8220;23px|55px|21px|55px|false|true&#8220; custom_padding_tablet=&#8220;23px|55px|21px|55px|false|true&#8220; custom_padding_phone=&#8220;19px|25px|16px|25px|false|true&#8220; custom_padding_last_edited=&#8220;on|phone&#8220; button_text_size_tablet=&#8220;15px&#8220; button_text_size_phone=&#8220;14px&#8220; button_text_size_last_edited=&#8220;on|phone&#8220; box_shadow_style=&#8220;preset1&#8243; global_colors_info=&#8220;{}&#8220; button_text_color__hover_enabled=&#8220;off|desktop&#8220; button_text_color__hover=&#8220;#ffffff&#8220; button_bg_color__hover_enabled=&#8220;off|desktop&#8220; button_bg_color__hover=&#8220;#75a099&#8243; button_bg_enable_color__hover=&#8220;on&#8220; button_border_color__hover_enabled=&#8220;on|hover&#8220; button_border_color__hover=&#8220;#2A3F75&#8243; button_letter_spacing__hover_enabled=&#8220;on|desktop&#8220; button_letter_spacing__hover=&#8220;1px&#8220; transform_styles__hover_enabled=&#8220;on|desktop&#8220; transform_scale__hover=&#8220;105%|105%&#8220; transform_scale__hover_enabled=&#8220;on|desktop&#8220; transform_translate__hover_enabled=&#8220;on|desktop&#8220; transform_rotate__hover_enabled=&#8220;on|desktop&#8220; transform_skew__hover_enabled=&#8220;on|desktop&#8220; transform_origin__hover_enabled=&#8220;on|desktop&#8220;][\/et_pb_button][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;Poppins|300|||||||&#8220; text_font_size=&#8220;16px&#8220; text_orientation=&#8220;center&#8220; custom_margin=&#8220;40px||||false|false&#8220; custom_margin_tablet=&#8220;&#8220; custom_margin_phone=&#8220;&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<p style=\"text-align: center;\">\ud83d\udd17 <a href=\"#konditionen\"><span style=\"text-decoration: underline;\">F\u00fcr eine klare und faire Zusammenarbeit<\/span><\/a><\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;39px|auto||auto|false|false&#8220; custom_margin_tablet=&#8220;31px|auto||auto|false|false&#8220; custom_margin_phone=&#8220;21px||||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; custom_padding=&#8220;||9px|||&#8220; animation_style=&#8220;fade&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_icon font_icon=&#8220;&#xf4be;||fa||900&#8243; icon_color=&#8220;#056F70&#8243; icon_width=&#8220;45px&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;5px|||||&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_icon][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; header_3_font=&#8220;Libre Caslon Text||||||||&#8220; header_3_text_align=&#8220;center&#8220; header_3_text_color=&#8220;#056F70&#8243; header_3_font_size=&#8220;30px&#8220; header_3_line_height=&#8220;1.4em&#8220; max_width=&#8220;700px&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;30px||||false|false&#8220; custom_margin_tablet=&#8220;-10px||||false|false&#8220; custom_margin_phone=&#8220;-10px||||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; header_3_font_size_tablet=&#8220;28px&#8220; header_3_font_size_phone=&#8220;28px&#8220; header_3_font_size_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<h3>F\u00fcr wen diese Begleitung ist:<\/h3>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_2,1_2&#8243; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;7px|auto||auto|false|false&#8220; custom_padding=&#8220;6px|||||&#8220; animation_style=&#8220;fade&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; header_3_font=&#8220;Libre Caslon Text||||||||&#8220; header_3_text_align=&#8220;left&#8220; header_3_text_color=&#8220;#056F70&#8243; header_3_font_size=&#8220;25px&#8220; header_3_line_height=&#8220;1.4em&#8220; max_width=&#8220;700px&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;30px||||false|false&#8220; custom_margin_tablet=&#8220;30px||||false|false&#8220; custom_margin_phone=&#8220;30px||||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; header_3_font_size_tablet=&#8220;28px&#8220; header_3_font_size_phone=&#8220;22px&#8220; header_3_font_size_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<h3>Diese Begleitung ist f\u00fcr dich, wenn\u2026<\/h3>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;Poppins|300|||||||&#8220; text_text_color=&#8220;#333333&#8243; text_font_size=&#8220;18px&#8220; text_line_height=&#8220;1.8em&#8220; custom_margin=&#8220;-5px||||false|false&#8220; custom_margin_tablet=&#8220;-15px||||false|false&#8220; custom_margin_phone=&#8220;-15px||||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<ul>\n<li>du nicht mehr nur Symptome behandeln willst, sondern wirklich verstehen willst, was dahinter steckt<\/li>\n<li>du bereit bist, auch dich mit einzubeziehen und Verantwortung f\u00fcr Ver\u00e4nderung zu \u00fcbernehmen<\/li>\n<li>du dir nachhaltige Ver\u00e4nderung w\u00fcnschst statt kurzfristiger \u201ees wird kurz besser\u201c-L\u00f6sungen<\/li>\n<\/ul>\n<p>\u2026und du sp\u00fcrst, dass ihr so nicht weitermachen k\u00f6nnt.<\/p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; header_3_font=&#8220;Libre Caslon Text||||||||&#8220; header_3_text_align=&#8220;left&#8220; header_3_text_color=&#8220;#056F70&#8243; header_3_font_size=&#8220;25px&#8220; header_3_line_height=&#8220;1.4em&#8220; max_width=&#8220;700px&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;30px||||false|false&#8220; custom_margin_tablet=&#8220;30px||||false|false&#8220; custom_margin_phone=&#8220;30px||||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; header_3_font_size_tablet=&#8220;28px&#8220; header_3_font_size_phone=&#8220;22px&#8220; header_3_font_size_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<h3> Diese Begleitung ist nicht f\u00fcr dich, wenn\u2026 <\/h3>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;Poppins|300|||||||&#8220; text_text_color=&#8220;#333333&#8243; text_font_size=&#8220;18px&#8220; text_line_height=&#8220;1.8em&#8220; custom_margin=&#8220;-5px||||false|false&#8220; custom_margin_tablet=&#8220;-15px||||false|false&#8220; custom_margin_phone=&#8220;-15px||||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<ul>\n<li>du eine schnelle L\u00f6sung suchst, ohne tiefer hinzuschauen<\/li>\n<li>du einfach nur Symptome \u201eweghaben\u201c willst<\/li>\n<li>du nicht bereit bist, Zeit, Energie und Ver\u00e4nderung zu investieren<\/li>\n<li>oder du hoffst, dass sich etwas \u00e4ndert, ohne dass du selbst Teil davon bist<\/li>\n<\/ul>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;Poppins|300|||||||&#8220; text_text_color=&#8220;#333333&#8243; text_font_size=&#8220;18px&#8220; text_line_height=&#8220;1.8em&#8220; custom_margin=&#8220;-5px||||false|false&#8220; custom_margin_tablet=&#8220;-15px||||false|false&#8220; custom_margin_phone=&#8220;-15px||||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<p style=\"text-align: center;\"><strong>Wenn du dich hier wiedererkennst, dann ist das kein Zufall.<\/strong><\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=&#8220;on|phone&#8220; module_id=&#8220;begleitunganfragen&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;29px|auto|92px|auto|false|false&#8220; custom_margin_tablet=&#8220;10px|auto||auto|false|false&#8220; custom_margin_phone=&#8220;0px||0px||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; custom_padding=&#8220;39px||0px|||&#8220; custom_padding_tablet=&#8220;||9px|||&#8220; custom_padding_phone=&#8220;||0px||false|false&#8220; animation_style=&#8220;fade&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_icon font_icon=&#8220;&#xf5bb;||fa||900&#8243; icon_color=&#8220;#056F70&#8243; icon_width=&#8220;45px&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;5px|||||&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_icon][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; header_3_font=&#8220;Libre Caslon Text||||||||&#8220; header_3_text_align=&#8220;center&#8220; header_3_text_color=&#8220;#056F70&#8243; header_3_font_size=&#8220;30px&#8220; header_3_line_height=&#8220;1.4em&#8220; max_width=&#8220;700px&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;30px||28px||false|false&#8220; custom_margin_tablet=&#8220;-10px||||false|false&#8220; custom_margin_phone=&#8220;-10px||||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; header_3_font_size_tablet=&#8220;28px&#8220; header_3_font_size_phone=&#8220;28px&#8220; header_3_font_size_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<h3> Du hast kein Hund, sondern ein anderes Tier? <\/h3>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;Poppins|300|||||||&#8220; text_text_color=&#8220;#333333&#8243; text_font_size=&#8220;18px&#8220; text_line_height=&#8220;1.8em&#8220; custom_margin=&#8220;-5px||||false|false&#8220; custom_margin_tablet=&#8220;-15px||||false|false&#8220; custom_margin_phone=&#8220;-15px||||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<p style=\"text-align: center;\">Die Art des Tieres ist nicht entscheidend. Entscheidend ist das, was zwischen euch wirkt. Auch wenn mein Fokus auf der Arbeit mit Menschen und Hunden liegt, ist diese systemische Arbeit nicht darauf begrenzt. Denn die Dynamiken entstehen im System zwischen euch, nicht durch die Tierart.<\/p>\n<p style=\"text-align: center;\">Wenn du sp\u00fcrst, dass sich genau solche Muster bei euch zeigen, dann kann diese Arbeit auch f\u00fcr euch der Schl\u00fcssel sein.<\/p>\n<p style=\"text-align: center;\">Im ersten Schritt schauen wir gemeinsam, ob und wie ich euch sinnvoll unterst\u00fctzen kann.<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;2&#8243; make_equal=&#8220;on&#8220; custom_padding_last_edited=&#8220;on|phone&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#FFFFFF&#8220; width=&#8220;90%&#8220; width_tablet=&#8220;90%&#8220; width_phone=&#8220;90%&#8220; width_last_edited=&#8220;on|desktop&#8220; max_width=&#8220;1170px&#8220; max_width_tablet=&#8220;90%&#8220; max_width_phone=&#8220;90%&#8220; max_width_last_edited=&#8220;on|tablet&#8220; custom_margin=&#8220;82px|auto||auto||&#8220; custom_margin_tablet=&#8220;65px|auto||auto|false|false&#8220; custom_margin_phone=&#8220;75px|auto||auto|false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; custom_padding=&#8220;60px|60px|60px|60px|false|true&#8220; custom_padding_tablet=&#8220;60px|30px|60px|30px|false|false&#8220; custom_padding_phone=&#8220;60px|30px|60px|30px|false|false&#8220; animation_style=&#8220;fade&#8220; border_radii=&#8220;on|20px|20px|20px|20px&#8220; border_color_right=&#8220;#056F70&#8243; border_color_bottom=&#8220;#056F70&#8243; box_shadow_style=&#8220;preset1&#8243; box_shadow_color=&#8220;#056F70&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_icon font_icon=&#8220;&#xf06e;||fa||400&#8243; icon_color=&#8220;#056F70&#8243; icon_width=&#8220;45px&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;5px|||||&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_icon][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; header_3_font=&#8220;Libre Caslon Text||||||||&#8220; header_3_text_align=&#8220;center&#8220; header_3_text_color=&#8220;#056F70&#8243; header_3_font_size=&#8220;30px&#8220; header_3_line_height=&#8220;1.4em&#8220; max_width=&#8220;700px&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;30px||||false|false&#8220; custom_margin_tablet=&#8220;-10px||||false|false&#8220; custom_margin_phone=&#8220;-10px||||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; header_3_font_size_tablet=&#8220;28px&#8220; header_3_font_size_phone=&#8220;28px&#8220; header_3_font_size_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<h3>\u00abDer Zwischenblick\u00bb \u2013 dein erster Schritt raus aus dem Kreislauf <\/h3>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;Poppins|300|||||||&#8220; text_text_color=&#8220;#333333&#8243; text_font_size=&#8220;18px&#8220; text_line_height=&#8220;1.8em&#8220; text_orientation=&#8220;center&#8220; custom_margin=&#8220;-5px||||false|false&#8220; custom_margin_tablet=&#8220;-15px||||false|false&#8220; custom_margin_phone=&#8220;-15px||||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<p>Du hast schon viel versucht und trotzdem dreht ihr euch im Kreis. Wenn du sp\u00fcrst, dass es so nicht weitergehen kann, dann ist das dein n\u00e4chster Schritt.<\/p>\n<p><strong><\/strong><\/p>\n<p><strong><br \/>Was passiert im Zwischenblick?<\/strong><\/p>\n<p>Wir schauen gemeinsam:<\/p>\n<p>\u2022 Wo ihr aktuell wirklich steht<\/p>\n<p>\u2022 Was bei deinem Hund\/Tier gerade im Vordergrund steht<\/p>\n<p>\u2022 Wie es dir in dieser Situation wirklich geht<\/p>\n<p>\u2022 Was der n\u00e4chste sinnvolle Schritt f\u00fcr euch ist<\/p>\n<p>\u2022 Ob die Begleitung \u201eBeide Enden der Leine\u201c f\u00fcr euch passt<\/p>\n<p>\u2022 Und ob die Chemie zwischen uns stimmt<\/p>\n<p>&nbsp;<\/p>\n<p>Du bekommst eine ehrliche Einsch\u00e4tzung, auch wenn ich sage, dass es (noch) nicht passt.<\/p>\n<p>30 Minuten Klarheitsgespr\u00e4ch inkl. Fragebogen vorab + erste individuelle Impulse<\/p>\n<p><strong>Deine Investition:<\/strong> 123 \u20ac<br \/>wird bei Buchung von \u201eBeide Enden der Leine\u201c vollst\u00e4ndig angerechnet<\/p>\n<p>Wenn du bereit bist, wirklich hinzuschauen, dann sichere dir jetzt deinen Termin.<\/p>[\/et_pb_text][et_pb_button button_url=&#8220;https:\/\/calendly.com\/aponi_naturopatia\/zwischenblick-deutsch&#8220; url_new_window=&#8220;on&#8220; button_text=&#8220;Zwischenblick jetzt buchen&#8220; button_alignment=&#8220;center&#8220; button_alignment_tablet=&#8220;center&#8220; button_alignment_phone=&#8220;center&#8220; button_alignment_last_edited=&#8220;off|desktop&#8220; disabled_on=&#8220;off|off|off&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;15px&#8220; button_text_color=&#8220;#000000&#8243; button_bg_color=&#8220;#A5E2D9&#8243; button_border_width=&#8220;0px&#8220; button_border_radius=&#8220;100px&#8220; button_letter_spacing=&#8220;1px&#8220; button_font=&#8220;Poppins|||on|||||&#8220; button_use_icon=&#8220;off&#8220; custom_margin=&#8220;50px||||false|false&#8220; custom_padding=&#8220;23px|55px|21px|55px|false|true&#8220; custom_padding_tablet=&#8220;23px|55px|21px|55px|false|true&#8220; custom_padding_phone=&#8220;19px|25px|16px|25px|false|true&#8220; custom_padding_last_edited=&#8220;on|phone&#8220; button_text_size_tablet=&#8220;15px&#8220; button_text_size_phone=&#8220;14px&#8220; button_text_size_last_edited=&#8220;on|phone&#8220; box_shadow_style=&#8220;preset1&#8243; global_colors_info=&#8220;{}&#8220; button_text_color__hover_enabled=&#8220;off|desktop&#8220; button_text_color__hover=&#8220;#ffffff&#8220; button_bg_color__hover_enabled=&#8220;off|desktop&#8220; button_bg_color__hover=&#8220;#75a099&#8243; button_bg_enable_color__hover=&#8220;on&#8220; button_border_color__hover_enabled=&#8220;on|hover&#8220; button_border_color__hover=&#8220;#2A3F75&#8243; button_letter_spacing__hover_enabled=&#8220;on|desktop&#8220; button_letter_spacing__hover=&#8220;1px&#8220; transform_styles__hover_enabled=&#8220;on|desktop&#8220; transform_scale__hover=&#8220;105%|105%&#8220; transform_scale__hover_enabled=&#8220;on|desktop&#8220; transform_translate__hover_enabled=&#8220;on|desktop&#8220; transform_rotate__hover_enabled=&#8220;on|desktop&#8220; transform_skew__hover_enabled=&#8220;on|desktop&#8220; transform_origin__hover_enabled=&#8220;on|desktop&#8220;][\/et_pb_button][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;Poppins|300|||||||&#8220; text_font_size=&#8220;16px&#8220; text_orientation=&#8220;center&#8220; custom_margin=&#8220;40px||||false|false&#8220; custom_margin_tablet=&#8220;&#8220; custom_margin_phone=&#8220;&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<p style=\"text-align: center;\">\ud83d\udd17 <a href=\"#konditionen\"><span style=\"text-decoration: underline;\">F\u00fcr eine klare und faire Zusammenarbeit<\/span><\/a><\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>\u201eBeide Enden der Leine\u201cWenn Symptome mehr sind als nur Symptome 8 Wochen systemische Ursachenarbeit f\u00fcr dich und deinen HundDu warst bei den verschiedenen Tier\u00e4rzten, hast Futter umgestellt und unterschiedliche Ans\u00e4tze probiert. Du hast alles versucht. Und trotzdem kommt es immer wieder zur\u00fcck. Und ganz ehrlich? Es macht dich langsam verr\u00fcckt. Du beobachtest st\u00e4ndig, analysierst jede [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":85972,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-86786","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Systemische Ursachenarbeit Hund | Aponi Naturopat\u00eda<\/title>\n<meta name=\"description\" content=\"Systemische Ursachenarbeit Hund: 8 Wochen f\u00fcr dich und deinen Hund \u2013 Symptome verstehen statt behandeln, f\u00fcr Ruhe und Stabilit\u00e4t im Alltag.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aponi.es\/en\/both-ends-of-the-leash\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Systemische Ursachenarbeit Hund | Aponi Naturopat\u00eda\" \/>\n<meta property=\"og:description\" content=\"Systemische Ursachenarbeit Hund: 8 Wochen f\u00fcr dich und deinen Hund \u2013 Symptome verstehen statt behandeln, f\u00fcr Ruhe und Stabilit\u00e4t im Alltag.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aponi.es\/en\/both-ends-of-the-leash\/\" \/>\n<meta property=\"og:site_name\" content=\"Aponi Naturopatia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-25T17:17:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aponi.es\/wp-content\/uploads\/2025\/12\/Aponi_Logo_neu.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aponi.es\\\/beide-enden-der-leine\\\/\",\"url\":\"https:\\\/\\\/aponi.es\\\/beide-enden-der-leine\\\/\",\"name\":\"Systemische Ursachenarbeit Hund | Aponi Naturopat\u00eda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aponi.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aponi.es\\\/beide-enden-der-leine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aponi.es\\\/beide-enden-der-leine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aponi.es\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Aponi_Logo_neu.webp\",\"datePublished\":\"2026-05-03T14:25:46+00:00\",\"dateModified\":\"2026-07-25T17:17:38+00:00\",\"description\":\"Systemische Ursachenarbeit Hund: 8 Wochen f\u00fcr dich und deinen Hund \u2013 Symptome verstehen statt behandeln, f\u00fcr Ruhe und Stabilit\u00e4t im Alltag.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aponi.es\\\/beide-enden-der-leine\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aponi.es\\\/beide-enden-der-leine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/aponi.es\\\/beide-enden-der-leine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aponi.es\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Aponi_Logo_neu.webp\",\"contentUrl\":\"https:\\\/\\\/aponi.es\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Aponi_Logo_neu.webp\",\"width\":1000,\"height\":1000,\"caption\":\"Aponi Naturopat\u00eda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aponi.es\\\/beide-enden-der-leine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/aponi.es\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201eBeide Enden der Leine\u201c\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aponi.es\\\/#website\",\"url\":\"https:\\\/\\\/aponi.es\\\/\",\"name\":\"Aponi Naturopat\u00eda\",\"description\":\"Naturheilkunde f\u00fcr Mensch und Tier\",\"publisher\":{\"@id\":\"https:\\\/\\\/aponi.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aponi.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aponi.es\\\/#organization\",\"name\":\"Aponi Naturopat\u00eda\",\"url\":\"https:\\\/\\\/aponi.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/aponi.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aponi.es\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Aponi_Logo.webp\",\"contentUrl\":\"https:\\\/\\\/aponi.es\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Aponi_Logo.webp\",\"width\":1000,\"height\":1000,\"caption\":\"Aponi Naturopat\u00eda\"},\"image\":{\"@id\":\"https:\\\/\\\/aponi.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Systemic Dog Therapy: Root-Cause Support, Online | Aponi","description":"8 weeks of root-cause work for you and your dog: understanding symptoms instead of treating them, on a physical, emotional and systemic level. Online.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aponi.es\/en\/both-ends-of-the-leash\/","og_locale":"en_US","og_type":"article","og_title":"Systemische Ursachenarbeit Hund | Aponi Naturopat\u00eda","og_description":"Systemische Ursachenarbeit Hund: 8 Wochen f\u00fcr dich und deinen Hund \u2013 Symptome verstehen statt behandeln, f\u00fcr Ruhe und Stabilit\u00e4t im Alltag.","og_url":"https:\/\/aponi.es\/en\/both-ends-of-the-leash\/","og_site_name":"Aponi Naturopatia","article_modified_time":"2026-07-25T17:17:38+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/aponi.es\/wp-content\/uploads\/2025\/12\/Aponi_Logo_neu.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aponi.es\/beide-enden-der-leine\/","url":"https:\/\/aponi.es\/beide-enden-der-leine\/","name":"Systemic Dog Therapy: Root-Cause Support, Online | Aponi","isPartOf":{"@id":"https:\/\/aponi.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aponi.es\/beide-enden-der-leine\/#primaryimage"},"image":{"@id":"https:\/\/aponi.es\/beide-enden-der-leine\/#primaryimage"},"thumbnailUrl":"https:\/\/aponi.es\/wp-content\/uploads\/2025\/12\/Aponi_Logo_neu.webp","datePublished":"2026-05-03T14:25:46+00:00","dateModified":"2026-07-25T17:17:38+00:00","description":"8 weeks of root-cause work for you and your dog: understanding symptoms instead of treating them, on a physical, emotional and systemic level. Online.","breadcrumb":{"@id":"https:\/\/aponi.es\/beide-enden-der-leine\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aponi.es\/beide-enden-der-leine\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/aponi.es\/beide-enden-der-leine\/#primaryimage","url":"https:\/\/aponi.es\/wp-content\/uploads\/2025\/12\/Aponi_Logo_neu.webp","contentUrl":"https:\/\/aponi.es\/wp-content\/uploads\/2025\/12\/Aponi_Logo_neu.webp","width":1000,"height":1000,"caption":"Aponi Naturopat\u00eda"},{"@type":"BreadcrumbList","@id":"https:\/\/aponi.es\/beide-enden-der-leine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/aponi.es\/de\/"},{"@type":"ListItem","position":2,"name":"\u201eBeide Enden der Leine\u201c\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/aponi.es\/#website","url":"https:\/\/aponi.es\/","name":"Aponi Naturopat\u00eda","description":"Naturopathy for Humans and Animals","publisher":{"@id":"https:\/\/aponi.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aponi.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/aponi.es\/#organization","name":"Aponi Naturopat\u00eda","url":"https:\/\/aponi.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/aponi.es\/#\/schema\/logo\/image\/","url":"https:\/\/aponi.es\/wp-content\/uploads\/2025\/11\/Aponi_Logo.webp","contentUrl":"https:\/\/aponi.es\/wp-content\/uploads\/2025\/11\/Aponi_Logo.webp","width":1000,"height":1000,"caption":"Aponi Naturopat\u00eda"},"image":{"@id":"https:\/\/aponi.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/aponi.es\/en\/wp-json\/wp\/v2\/pages\/86786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aponi.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aponi.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aponi.es\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aponi.es\/en\/wp-json\/wp\/v2\/comments?post=86786"}],"version-history":[{"count":28,"href":"https:\/\/aponi.es\/en\/wp-json\/wp\/v2\/pages\/86786\/revisions"}],"predecessor-version":[{"id":87156,"href":"https:\/\/aponi.es\/en\/wp-json\/wp\/v2\/pages\/86786\/revisions\/87156"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aponi.es\/en\/wp-json\/wp\/v2\/media\/85972"}],"wp:attachment":[{"href":"https:\/\/aponi.es\/en\/wp-json\/wp\/v2\/media?parent=86786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}